

{"id":15289,"date":"2026-05-13T10:06:55","date_gmt":"2026-05-13T08:06:55","guid":{"rendered":"https:\/\/fapacastello.com\/?p=15289\/"},"modified":"2026-05-13T10:09:18","modified_gmt":"2026-05-13T08:09:18","slug":"formacio-en-linia-promovent-la-salut-mental-en-ladolescencia","status":"publish","type":"post","link":"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/","title":{"rendered":"Formaci\u00f3n en l\u00ednea \u00abPromoviendo la salud mental en la adolescencia\u00bb\ufffc"},"content":{"rendered":"\n<p>La FAMPA Castell\u00f3 Penyagolosa, en colaboraci\u00f3n con la AFA del IES Ribalta, organiza la charla en l\u00ednea \u00abPromoviendo la salud mental en la adolescencia\u00bb dentro del programa de formaci\u00f3n para familias \u00abLa FAMPA et forma 2025-2026\u00bb.<\/p>\n\n\n\n<p>La adolescencia conlleva cambios cerebrales significativos y nuevos retos de convivencia. Esta sesi\u00f3n, impartida por la psic\u00f3loga sanitaria y orientadora educativa Aida Fern\u00e1ndez, dotar\u00e1 a las familias de estrategias pr\u00e1cticas para fomentar h\u00e1bitos saludables e identificar problemas comunes de salud mental. El objetivo es ofrecer herramientas para acompa\u00f1ar a los j\u00f3venes en la gesti\u00f3n de las tensiones diarias, favoreciendo un desarrollo pleno que no dependa exclusivamente del refugio en el mundo digital.<\/p>\n\n\n\n<p><strong>Datos de la sesi\u00f3n:<\/strong><\/p>\n\n\n\n<ul><li><strong>Fecha:<\/strong> mi\u00e9rcoles 27 de mayo a las 18 h<\/li><li><strong>Duraci\u00f3n:<\/strong> 1 h y media<\/li><li><strong>Formato:<\/strong> en l\u00ednea<\/li><li><strong>P\u00fablico recomendado:<\/strong> familias de ni\u00f1os y ni\u00f1as a partir de 12 a\u00f1os<\/li><li><strong>Inscripci\u00f3n:<\/strong> hasta el 27 de mayo a las 12 h a trav\u00e9s de este formulario <a href=\"https:\/\/forms.gle\/m43u5C2PBiwE3bWt8\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/forms.gle\/m43u5C2PBiwE3bWt8<\/a><\/li><\/ul>\n\n\n\n<p>El enlace de acceso se compartir\u00e1 exclusivamente con las personas inscritas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"819\" height=\"1024\" src=\"https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/Promoviendo-la-salud-mental-en-la-adolescencia-819x1024.jpg\" alt=\"\" class=\"wp-image-15287\" srcset=\"https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/Promoviendo-la-salud-mental-en-la-adolescencia-819x1024.jpg 819w, https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/Promoviendo-la-salud-mental-en-la-adolescencia-240x300.jpg 240w, https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/Promoviendo-la-salud-mental-en-la-adolescencia-768x960.jpg 768w, https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/Promoviendo-la-salud-mental-en-la-adolescencia-117x146.jpg 117w, https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/Promoviendo-la-salud-mental-en-la-adolescencia-40x50.jpg 40w, https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/Promoviendo-la-salud-mental-en-la-adolescencia-60x75.jpg 60w, https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/Promoviendo-la-salud-mental-en-la-adolescencia-640x800.jpg 640w, https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/Promoviendo-la-salud-mental-en-la-adolescencia.jpg 1080w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La FAMPA, en colaboraci\u00f3n con la AFA del IES Ribalta, organiza la charla en l\u00ednea \u00abPromoviendo la salud mental en la adolescencia\u00bb<\/p>\n","protected":false},"author":10,"featured_media":15281,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Formaci\u00f3n en l\u00ednea &quot;Promoviendo la salud mental en la adolescencia&quot;\ufffc<\/title>\n<meta name=\"description\" content=\"La FAMPA, en colaboraci\u00f3n con la AFA del IES Ribalta, organiza la charla en l\u00ednea \u00abPromoviendo la salud mental en la adolescencia\u00bb\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formaci\u00f3n en l\u00ednea &quot;Promoviendo la salud mental en la adolescencia&quot;\ufffc\" \/>\n<meta property=\"og:description\" content=\"La FAMPA, en colaboraci\u00f3n con la AFA del IES Ribalta, organiza la charla en l\u00ednea \u00abPromoviendo la salud mental en la adolescencia\u00bb\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/\" \/>\n<meta property=\"og:site_name\" content=\"FAMPA Castell\u00f3 Penyagolosa\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/fapa.penyagolosa\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T08:06:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T08:09:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/BANNERS-WEB-2-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Raquel Garc\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:creator\" content=\"@FAMPACS\" \/>\n<meta name=\"twitter:site\" content=\"@FAMPACS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Raquel Garc\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/fapacastello.com\/es\/#website\",\"url\":\"http:\/\/fapacastello.com\/es\/\",\"name\":\"FAMPA Castell\u00f3 Penyagolosa\",\"description\":\"Fapa-Castell\u00f3n Penyagolosa. Federaci\u00f3n de Asociaciones de Padres i Madres de Alumnos Provincia de Castell\u00f3n.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/fapacastello.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/#primaryimage\",\"url\":\"https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/BANNERS-WEB-2-1.jpg\",\"contentUrl\":\"https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/BANNERS-WEB-2-1.jpg\",\"width\":2000,\"height\":875},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/#webpage\",\"url\":\"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/\",\"name\":\"Formaci\u00f3n en l\u00ednea \\\"Promoviendo la salud mental en la adolescencia\\\"\ufffc\",\"isPartOf\":{\"@id\":\"http:\/\/fapacastello.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/#primaryimage\"},\"datePublished\":\"2026-05-13T08:06:55+00:00\",\"dateModified\":\"2026-05-13T08:09:18+00:00\",\"author\":{\"@id\":\"http:\/\/fapacastello.com\/es\/#\/schema\/person\/91d59e41a269f5dee4a303027882f840\"},\"description\":\"La FAMPA, en colaboraci\u00f3n con la AFA del IES Ribalta, organiza la charla en l\u00ednea \u00abPromoviendo la salud mental en la adolescencia\u00bb\",\"breadcrumb\":{\"@id\":\"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/fapacastello.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Formaci\u00f3n en l\u00ednea \u00abPromoviendo la salud mental en la adolescencia\u00bb\ufffc\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/fapacastello.com\/es\/#\/schema\/person\/91d59e41a269f5dee4a303027882f840\",\"name\":\"Raquel Garc\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\/\/fapacastello.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/55ba383e1db6bbbe8adcbe85e4cbe60d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/55ba383e1db6bbbe8adcbe85e4cbe60d?s=96&d=mm&r=g\",\"caption\":\"Raquel Garc\u00eda\"},\"url\":\"https:\/\/fapacastello.com\/es\/author\/socraquel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formaci\u00f3n en l\u00ednea \"Promoviendo la salud mental en la adolescencia\"\ufffc","description":"La FAMPA, en colaboraci\u00f3n con la AFA del IES Ribalta, organiza la charla en l\u00ednea \u00abPromoviendo la salud mental en la adolescencia\u00bb","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/","og_locale":"es_ES","og_type":"article","og_title":"Formaci\u00f3n en l\u00ednea \"Promoviendo la salud mental en la adolescencia\"\ufffc","og_description":"La FAMPA, en colaboraci\u00f3n con la AFA del IES Ribalta, organiza la charla en l\u00ednea \u00abPromoviendo la salud mental en la adolescencia\u00bb","og_url":"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/","og_site_name":"FAMPA Castell\u00f3 Penyagolosa","article_publisher":"http:\/\/www.facebook.com\/fapa.penyagolosa","article_published_time":"2026-05-13T08:06:55+00:00","article_modified_time":"2026-05-13T08:09:18+00:00","og_image":[{"width":2000,"height":875,"url":"https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/BANNERS-WEB-2-1.jpg","type":"image\/jpeg"}],"author":"Raquel Garc\u00eda","twitter_card":"summary","twitter_creator":"@FAMPACS","twitter_site":"@FAMPACS","twitter_misc":{"Escrito por":"Raquel Garc\u00eda","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/fapacastello.com\/es\/#website","url":"http:\/\/fapacastello.com\/es\/","name":"FAMPA Castell\u00f3 Penyagolosa","description":"Fapa-Castell\u00f3n Penyagolosa. Federaci\u00f3n de Asociaciones de Padres i Madres de Alumnos Provincia de Castell\u00f3n.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/fapacastello.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/#primaryimage","url":"https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/BANNERS-WEB-2-1.jpg","contentUrl":"https:\/\/fapacastello.com\/wp-content\/uploads\/2026\/05\/BANNERS-WEB-2-1.jpg","width":2000,"height":875},{"@type":"WebPage","@id":"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/#webpage","url":"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/","name":"Formaci\u00f3n en l\u00ednea \"Promoviendo la salud mental en la adolescencia\"\ufffc","isPartOf":{"@id":"http:\/\/fapacastello.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/#primaryimage"},"datePublished":"2026-05-13T08:06:55+00:00","dateModified":"2026-05-13T08:09:18+00:00","author":{"@id":"http:\/\/fapacastello.com\/es\/#\/schema\/person\/91d59e41a269f5dee4a303027882f840"},"description":"La FAMPA, en colaboraci\u00f3n con la AFA del IES Ribalta, organiza la charla en l\u00ednea \u00abPromoviendo la salud mental en la adolescencia\u00bb","breadcrumb":{"@id":"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fapacastello.com\/es\/2026\/05\/13\/formacio-en-linia-promovent-la-salut-mental-en-ladolescencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/fapacastello.com\/es\/"},{"@type":"ListItem","position":2,"name":"Formaci\u00f3n en l\u00ednea \u00abPromoviendo la salud mental en la adolescencia\u00bb\ufffc"}]},{"@type":"Person","@id":"http:\/\/fapacastello.com\/es\/#\/schema\/person\/91d59e41a269f5dee4a303027882f840","name":"Raquel Garc\u00eda","image":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/fapacastello.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/55ba383e1db6bbbe8adcbe85e4cbe60d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/55ba383e1db6bbbe8adcbe85e4cbe60d?s=96&d=mm&r=g","caption":"Raquel Garc\u00eda"},"url":"https:\/\/fapacastello.com\/es\/author\/socraquel\/"}]}},"_links":{"self":[{"href":"https:\/\/fapacastello.com\/es\/wp-json\/wp\/v2\/posts\/15289"}],"collection":[{"href":"https:\/\/fapacastello.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fapacastello.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fapacastello.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/fapacastello.com\/es\/wp-json\/wp\/v2\/comments?post=15289"}],"version-history":[{"count":2,"href":"https:\/\/fapacastello.com\/es\/wp-json\/wp\/v2\/posts\/15289\/revisions"}],"predecessor-version":[{"id":15292,"href":"https:\/\/fapacastello.com\/es\/wp-json\/wp\/v2\/posts\/15289\/revisions\/15292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fapacastello.com\/es\/wp-json\/wp\/v2\/media\/15281"}],"wp:attachment":[{"href":"https:\/\/fapacastello.com\/es\/wp-json\/wp\/v2\/media?parent=15289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fapacastello.com\/es\/wp-json\/wp\/v2\/categories?post=15289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fapacastello.com\/es\/wp-json\/wp\/v2\/tags?post=15289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}